{"id":5959,"date":"2018-11-23T17:05:00","date_gmt":"2018-11-23T17:05:00","guid":{"rendered":"https:\/\/www.litepoint.com\/careers\/university-programs\/"},"modified":"2019-06-20T22:32:54","modified_gmt":"2019-06-20T22:32:54","slug":"university-programs","status":"publish","type":"page","link":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/","title":{"rendered":"\u9ad8\u6821\u9879\u76ee"},"content":{"rendered":"<h2>\u65b0\u4e00\u4ee3\u6280\u672f\u4e9f\u9700\u65b0\u4e00\u4ee3\u521b\u65b0\u4eba\u624d<\/h2>\n<p>LitePoint \u5c06\u4eba\u624d\u89c6\u4e3a\u6700\u5b9d\u8d35\u7684\u8d44\u6e90\u3002\u56e0\u6b64\u4e0d\u96be\u7406\u89e3\uff0c\u52a9\u529b\u57f9\u517b\u65b0\u5458\u5de5\u81f3\u5173\u91cd\u8981\u3002 LitePoint \u9ad8\u6821\u9879\u76ee\u662f\u6211\u4eec\u4e0e\u65b0\u4e00\u4ee3\u601d\u60f3\u5bb6\u3001\u8bbe\u8ba1\u5e08\u548c\u521b\u9020\u8005\u4ea4\u6d41\u4e92\u52a8\u7684\u91cd\u8981\u9014\u5f84\u3002\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u65b0\u4e00\u4ee3\u6280\u672f\u4e9f\u9700\u65b0\u4e00\u4ee3\u521b\u65b0\u4eba\u624d LitePoint \u5c06\u4eba\u624d\u89c6\u4e3a\u6700\u5b9d\u8d35\u7684\u8d44\u6e90\u3002\u56e0\u6b64\u4e0d\u96be\u7406\u89e3\uff0c\u52a9\u529b\u57f9\u517b\u65b0\u5458\u5de5\u81f3\u5173\u91cd\u8981&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":5951,"menu_order":19,"comment_status":"closed","ping_status":"closed","template":"template-university.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"tags":[],"class_list":["post-5959","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u9ad8\u6821\u9879\u76ee - LitePoint<\/title>\n<meta name=\"description\" content=\"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u9ad8\u6821\u9879\u76ee\" \/>\n<meta property=\"og:description\" content=\"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/\" \/>\n<meta property=\"og:site_name\" content=\"LitePoint\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/litepointcorporation\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-20T22:32:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@litepoint\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/university-programs\\\/\",\"url\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/university-programs\\\/\",\"name\":\"\u9ad8\u6821\u9879\u76ee - LitePoint\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2018-11-23T17:05:00+00:00\",\"dateModified\":\"2019-06-20T22:32:54+00:00\",\"description\":\"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/university-programs\\\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/university-programs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/university-programs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u62db\u8d24\u7eb3\u58eb\",\"item\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/careers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u9ad8\u6821\u9879\u76ee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/\",\"name\":\"LitePoint\",\"description\":\"Leader of Wireless Testing Innovations\",\"publisher\":{\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#organization\",\"name\":\"LitePoint\",\"url\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CN\",\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LP.png\",\"contentUrl\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LP.png\",\"width\":90,\"height\":14,\"caption\":\"LitePoint\"},\"image\":{\"@id\":\"https:\\\/\\\/litepointstage.wpengine.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/litepointcorporation\",\"https:\\\/\\\/x.com\\\/litepoint\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/litepoint\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/LitePoint\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u9ad8\u6821\u9879\u76ee - LitePoint","description":"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/","og_locale":"zh_CN","og_type":"article","og_title":"\u9ad8\u6821\u9879\u76ee","og_description":"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002","og_url":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/","og_site_name":"LitePoint","article_publisher":"https:\/\/www.facebook.com\/litepointcorporation","article_modified_time":"2019-06-20T22:32:54+00:00","twitter_card":"summary_large_image","twitter_site":"@litepoint","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/","url":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/","name":"\u9ad8\u6821\u9879\u76ee - LitePoint","isPartOf":{"@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#website"},"datePublished":"2018-11-23T17:05:00+00:00","dateModified":"2019-06-20T22:32:54+00:00","description":"\u6211\u4eec\u5f00\u8bbe\u4e24\u4e2a\u9ad8\u6821\u9879\u76ee: \u5e26\u85aa\u5b9e\u4e60\u9879\u76ee\u548c\u5e94\u5c4a\u9ad8\u6821\u6bd5\u4e1a\u751f\u9879\u76ee\u3002\u6bcf\u4e2a\u9879\u76ee\u7684\u53c2\u4e0e\u8005\u90fd\u53ef\u4ee5\u4e0e\u5145\u6ee1\u6d3b\u529b\u548c\u5e72\u52b2\u7684\u540c\u4e8b\u4e00\u8d77\u5171\u4e8b\uff0c\u4f53\u9a8c\u5c16\u7aef\u6280\u672f\uff0c\u4eab\u53d7\u5305\u5bb9\u7684\u516c\u53f8\u6587\u5316\u548c\u5bbd\u677e\u7684\u5de5\u4f5c\u73af\u5883\uff0c\u540c\u65f6\u8fd8\u6709\u673a\u4f1a\u5728\u5176\u4e2d\u53d1\u6325\u771f\u6b63\u7684\u6f5c\u529b\u3002","breadcrumb":{"@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/university-programs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/litepointstage.wpengine.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u62db\u8d24\u7eb3\u58eb","item":"https:\/\/litepointstage.wpengine.com\/zh-hans\/careers\/"},{"@type":"ListItem","position":3,"name":"\u9ad8\u6821\u9879\u76ee"}]},{"@type":"WebSite","@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#website","url":"https:\/\/litepointstage.wpengine.com\/zh-hans\/","name":"LitePoint","description":"Leader of Wireless Testing Innovations","publisher":{"@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/litepointstage.wpengine.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-CN"},{"@type":"Organization","@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#organization","name":"LitePoint","url":"https:\/\/litepointstage.wpengine.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-CN","@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/litepointstage.wpengine.com\/wp-content\/uploads\/2019\/05\/LP.png","contentUrl":"https:\/\/litepointstage.wpengine.com\/wp-content\/uploads\/2019\/05\/LP.png","width":90,"height":14,"caption":"LitePoint"},"image":{"@id":"https:\/\/litepointstage.wpengine.com\/zh-hans\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/litepointcorporation","https:\/\/x.com\/litepoint","http:\/\/www.linkedin.com\/company\/litepoint","http:\/\/www.youtube.com\/user\/LitePoint"]}]}},"_links":{"self":[{"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/pages\/5959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=5959"}],"version-history":[{"count":0,"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/pages\/5959\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/pages\/5951"}],"wp:attachment":[{"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=5959"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litepointstage.wpengine.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=5959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}